{"id":11314,"date":"2023-11-09T10:25:27","date_gmt":"2023-11-09T09:25:27","guid":{"rendered":"https:\/\/www.19paulfort.com\/galerie\/?p=11314"},"modified":"2025-03-01T08:23:02","modified_gmt":"2025-03-01T07:23:02","slug":"exposition-objets-inanimes-avez-vous-donc-une-ame-du-26-novembre-au-17-decembre-2023","status":"publish","type":"post","link":"http:\/\/www.19paulfort.com\/galerie\/index.php\/2023\/11\/09\/exposition-objets-inanimes-avez-vous-donc-une-ame-du-26-novembre-au-17-decembre-2023\/","title":{"rendered":"11 &#8211; 26 nov. \/ 17 d\u00e9c. &#8211; Exposition &#8211; \u00ab\u00a0Objets inanim\u00e9s, avez-vous donc une \u00e2me&#8230; ?\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11311\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/Expo_26Nov-JPEG.jpg\" alt=\"\" width=\"539\" height=\"781\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/Expo_26Nov-JPEG.jpg 539w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/Expo_26Nov-JPEG-207x300.jpg 207w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ces trois artistes sont r\u00e9unis sur un m\u00eame th\u00e8me<br \/>\n<a href=\"https:\/\/www.19paulfort.com\/galerie\/index.php\/2020\/10\/17\/monod-ginette\/\" target=\"_blank\" rel=\"noopener\">Ginette Monod <\/a><\/strong>sauve, redonne vie et r\u00e9v\u00e8le l\u2019\u00e2me des vieux v\u00eatements, \u00e9lim\u00e9s, rapi\u00e9c\u00e9s, repris\u00e9s, r\u00e9par\u00e9s, et les transforme en \u0153uvres d\u2019art.<br \/>\nL\u2019histoire qu\u2019elle raconte alors, est l\u00e0 pour perp\u00e9tuer la m\u00e9moire.<\/p>\n<p style=\"text-align: justify;\">Les photographes <a href=\"https:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/05\/16\/leriche-dany-finckinger-jean-michel\/\" target=\"_blank\" rel=\"noopener\"><strong>Dany Leriche<\/strong> et <strong>Jean-Michel Fickinger<\/strong><\/a>, arpentent le Mali depuis des ann\u00e9es. Ils \u00ab fixent \u00bb ce qu&rsquo;ils voient et au del\u00e0 de ce qu&rsquo;ils voient. Leur rencontre avec Yaya Coulibaly, ma\u00eetre de la marionnette, a abouti \u00e0 la naissance du livre \u00ab Sogobo, le monde des marionnettes \u00bb<br \/>\n\u00ab Yaya est le p\u00e8re et l\u2019enfant d\u2019une foule habit\u00e9e d\u2019histoires, habit\u00e9e des forces de la nature et de l\u2019esprit qui l\u2019ont enfant\u00e9e. Le sourire et la m\u00e9ditation auxquels invite la figure de bois sculpt\u00e9, sont l\u2019\u00e2me de son talent magique.\u00bb<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/06\/06\/loughran-patrick\/\" target=\"_blank\" rel=\"noopener\"><strong>Patrick Loughran<\/strong><\/a> donne vie \u00e0 ses sculptures. Il requestionne son travail en permanence, en s\u2019affranchissant du temps. Ses sculptures \u00e9voluent en fonction des situations. \u00ab L\u2019ensemble constitue un vocabulaire de formes allant de la repr\u00e9sentation v\u00e9g\u00e9tale ou organique, jusqu\u2019\u00e0 des formes plus abstraites assembl\u00e9es dans un id\u00e9al d\u2019harmonie.\u00bb<\/p>\n<div id='gallery-1' class='gallery galleryid-11314 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy-1024x1024.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy-300x300.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy-150x150.jpg 150w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy-768x768.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy-750x750.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128171114-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128193622-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128193622-Copy-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128193622-Copy-768x1024.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128193622-Copy-225x300.jpg 225w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128193622-Copy-750x1000.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231128193622-Copy.jpg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129170513-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129170513-Copy-1024x724.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129170513-Copy-1024x724.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129170513-Copy-300x212.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129170513-Copy-768x543.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129170513-Copy-750x530.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129170513-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171210-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171210-Copy-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171210-Copy-1024x768.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171210-Copy-300x225.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171210-Copy-768x576.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171210-Copy-750x563.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171210-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171328-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171328-Copy-1024x724.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171328-Copy-1024x724.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171328-Copy-300x212.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171328-Copy-768x543.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171328-Copy-750x530.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171328-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171512-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171512-Copy-1024x724.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171512-Copy-1024x724.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171512-Copy-300x212.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171512-Copy-768x543.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171512-Copy-750x530.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129171512-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy-1024x1024.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy-300x300.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy-150x150.jpg 150w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy-768x768.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy-750x750.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129173709-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174140-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174140-Copy-724x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174140-Copy-724x1024.jpg 724w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174140-Copy-212x300.jpg 212w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174140-Copy-768x1086.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174140-Copy-750x1061.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174140-Copy.jpg 905w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy-1024x1024.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy-300x300.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy-150x150.jpg 150w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy-768x768.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy-750x750.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174247-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174359-Copy.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174359-Copy-1024x724.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174359-Copy-1024x724.jpg 1024w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174359-Copy-300x212.jpg 300w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174359-Copy-768x543.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174359-Copy-750x530.jpg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/12\/20231129174359-Copy.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>&gt; <a href=\"https:\/\/www.19paulfort.com\/galerie\/index.php\/2020\/10\/17\/monod-ginette\/\" target=\"_blank\" rel=\"noopener\">voir la fiche de Ginette Monod<\/a><\/strong><br \/>\n<strong>&gt; <a href=\"https:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/05\/16\/leriche-dany-finckinger-jean-michel\/\" target=\"_blank\" rel=\"noopener\">voir la fiche de Dany Leriche et Jean-Michel Fickinger <\/a><\/strong><br \/>\n<strong>&gt; <a href=\"https:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/06\/06\/loughran-patrick\/\" target=\"_blank\" rel=\"noopener\">voir la fiche de Patrick Loughran<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>Bijoux textiles de Ginette Monod<\/strong><\/p>\n<div id='gallery-2' class='gallery galleryid-11314 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-scaled.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"973\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-973x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-973x1024.jpeg 973w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-285x300.jpeg 285w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-768x809.jpeg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-1459x1536.jpeg 1459w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-1945x2048.jpeg 1945w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-750x790.jpeg 750w\" sizes=\"auto, (max-width: 973px) 100vw, 973px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-scaled.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-720x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-720x1024.jpeg 720w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-211x300.jpeg 211w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-768x1093.jpeg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-1080x1536.jpeg 1080w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-1440x2048.jpeg 1440w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-750x1067.jpeg 750w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/FullSizeRender-2-scaled.jpeg 1800w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-scaled.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"965\" height=\"1024\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-965x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-965x1024.jpeg 965w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-283x300.jpeg 283w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-768x815.jpeg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-1448x1536.jpeg 1448w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-1930x2048.jpeg 1930w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2023\/11\/IMG_0772-750x796.jpeg 750w\" sizes=\"auto, (max-width: 965px) 100vw, 965px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ces trois artistes sont r\u00e9unis sur un m\u00eame th\u00e8me Ginette Monod sauve, redonne vie et r\u00e9v\u00e8le l\u2019\u00e2me des vieux v\u00eatements, \u00e9lim\u00e9s, rapi\u00e9c\u00e9s, repris\u00e9s, r\u00e9par\u00e9s, et les transforme en \u0153uvres d\u2019art. L\u2019histoire qu\u2019elle raconte alors, est l\u00e0 pour perp\u00e9tuer la m\u00e9moire. Les photographes Dany Leriche et Jean-Michel Fickinger, arpentent le Mali depuis des ann\u00e9es. Ils \u00ab&hellip;<a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2023\/11\/09\/exposition-objets-inanimes-avez-vous-donc-une-ame-du-26-novembre-au-17-decembre-2023\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">11 &#8211; 26 nov. \/ 17 d\u00e9c. &#8211; Exposition &#8211; \u00ab\u00a0Objets inanim\u00e9s, avez-vous donc une \u00e2me&#8230; ?\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60,15,16],"tags":[],"class_list":["post-11314","post","type-post","status-publish","format-standard","hentry","category-evenements-2023","category-evenements-futurs-ou-en-cours","category-expositions"],"_links":{"self":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/11314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/comments?post=11314"}],"version-history":[{"count":7,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/11314\/revisions"}],"predecessor-version":[{"id":12813,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/11314\/revisions\/12813"}],"wp:attachment":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/media?parent=11314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/categories?post=11314"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/tags?post=11314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}