{"id":4180,"date":"2016-11-23T18:49:57","date_gmt":"2016-11-23T17:49:57","guid":{"rendered":"http:\/\/www.19paulfort.com\/galerie\/?p=4180"},"modified":"2018-06-19T19:18:10","modified_gmt":"2018-06-19T18:18:10","slug":"beziat-philippe","status":"publish","type":"post","link":"http:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/11\/23\/beziat-philippe\/","title":{"rendered":"B\u00c9ZIAT Philippe \u2022"},"content":{"rendered":"<h1><a href=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2017\/01\/PhilippeBEZIAT.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4318\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2017\/01\/PhilippeBEZIAT.png\" alt=\"\" width=\"567\" height=\"1008\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2017\/01\/PhilippeBEZIAT.png 567w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2017\/01\/PhilippeBEZIAT-169x300.png 169w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/a><br \/>\nPhilippe B\u00e9ziat<\/h1>\n<p style=\"text-align: justify;\"><strong>R\u00e9alisateur<\/strong><\/p>\n<p style=\"text-align: justify;\"><em><strong>(&gt; English below)<\/strong><\/em><br \/>\nPhilippe B\u00e9ziat a r\u00e9alis\u00e9 de nombreux films documentaires tels que <em>Passions d\u2019op\u00e9ra \u2013 60 ans d\u2019art lyrique<\/em> \u00e0 Aix-en-Provence (2008) ou <em>De m\u00e9moire d\u2019orchestre<\/em> avec l\u2019Orchestre National de France (2004). Il a collabor\u00e9 avec le chef et claveciniste italien Rinaldo Alessandrini pour, entre autres, les <em>Gloria<\/em> de Vivaldi (2010) ou <em>Les Quatre Saisons d\u2019Antoine<\/em> (2012) cor\u00e9alis\u00e9 avec Gordon. Il a \u00e9galement r\u00e9alis\u00e9 plusieurs films avec le concours de Marc Minkowski, parmi lesquels Les musiciens du Louvre &#8211; <em>Paroles d\u2019orchestre<\/em> (2003), <em>Pour Sainte-C\u00e9cile<\/em> (2009), <em>Berlioz \u00e0 Versailles<\/em> (2011) et le documentaire-op\u00e9ra <em>Pell\u00e9as et M\u00e9lisande, le chant des aveugles<\/em> dans une mise en sc\u00e8ne d\u2019Olivier Py, sorti en salle en mars 2009.<\/p>\n<p style=\"text-align: justify;\">Lors de l\u2019\u00e9dition 2007 du Verbier Festival, Philippe B\u00e9ziat r\u00e9alise la diffusion en direct sur le web de onze concerts. Il a par ailleurs film\u00e9 deux spectacles mis en sc\u00e8ne par Giorgio Barberio Corsetti et Pierrick Sorin, <em>La pietra del paragone<\/em>, de Gioacchino Rossini (dont le DVD a re\u00e7u le Diapason d\u2019Or) et <em>Pop\u2019pea<\/em>, op\u00e9ra rock d\u2019apr\u00e8s Monteverdi. Il a \u00e9galement film\u00e9 <em>Der Ring des Nibelungen<\/em>, de Richard Wagner et <em>Pell\u00e9as et M\u00e9lisande<\/em>, de Claude Debussy, tous deux dans des productions de Robert Wilson, <em>Tourbillons<\/em> de Georges Aperghis et Olivier Cadiot,<em> Ta Bouche<\/em> de Maurice Yvain et <em>Docteur Ox<\/em> de Jacques Offenbach par la compagnie Les Brigands, la mise en sc\u00e8ne d\u2019Olivier Py des Contes d\u2019Hoffmann, celle de <em>Falstaff<\/em> par Dominique Pitoiset, celle du <em>Couronnement de Popp\u00e9e<\/em> par Jean-Fran\u00e7ois Sivadier, le ballet <em>Caligula<\/em> de Nicolas Le Riche et Guillaume Gallienne, la pi\u00e8ce <em>Th\u00e9\u00e2tre sans animaux<\/em> de Jean-Michel Ribes, ainsi que <em>Ring Saga<\/em>, version de l\u2019Anneau du Nibelung de Richard Wagner mise en sc\u00e8ne par Antoine Gindt. Philippe B\u00e9ziat a \u00e9galement r\u00e9alis\u00e9 plusieurs courts-m\u00e9trages de fiction.<br \/>\nEn f\u00e9vrier 2012 est sorti en salle son film <em>Noces<\/em> relatant la relation entre Ramuz et Stravinski autour de la cr\u00e9ation de la pi\u00e8ce \u00e9ponyme. En octobre de la m\u00eame ann\u00e9e sort <em>Traviata et nous<\/em>, un documentaire-op\u00e9ra sur le travail de mise en sc\u00e8ne conduit par Jean-Fran\u00e7ois Sivadier, dans le cadre du Festival d\u2019Aix-en-Provence 2011, avec Natalie Dessay ainsi que Louis Langr\u00e9e \u00e0 la t\u00eate du London Symphony Orchestra, pr\u00e9sent\u00e9 notamment au 50e Festival du Film de New York.<\/p>\n<p style=\"text-align: justify;\">En 2012 est sorti en salle son film Noces relatant la relation entre Ramuz et Stravinski autour de la cre\u0301ation de la pie\u0300ce e\u0301ponyme puis Traviata et nous, un documentaire-ope\u0301ra sur le travail de mise en sce\u0300ne conduit par Jean-Franc\u0327ois Sivadier, dans le cadre du Festival d\u2019Aix-en-Provence 2011, avec Natalie Dessay et Louis Langre\u0301e a\u0300 la te\u0302te du London Symphony Orchestra pre\u0301sente\u0301 notamment au 50e\u0300me Festival du Film de New York.<br \/>\nRe\u0301cemment Philippe Be\u0301ziat a re\u0301alise\u0301 le film Giordano Bruno sur l\u2019ope\u0301ra de Francesco Filidei mis en sce\u0300ne par Antoine Gindt (2016), Monteverdi, aux sources de l\u2019ope\u0301ra, diffuse\u0301 sur Arte en juin 2017 et Pre\u0301vert, paroles inattendues diffuse\u0301 sur France 2 en octobre 2017.<\/p>\n<p style=\"text-align: justify;\">En 2018, il a mis en sce\u0300ne et re\u0301alise\u0301 la partie vide\u0301o de Pelleas et Melisande a\u0300 Bordeaux (direction Mark Minkowski).<\/p>\n<p><strong>Philippe B\u00e9ziat<\/strong><strong>, live film direction<\/strong><\/p>\n<p style=\"text-align: justify;\">Philippe B\u00e9ziat has directed a number of documentaries, including Passions d&rsquo;op\u00e9ra \u2013 60 ans d&rsquo;art lyrique \u00e0 Aix-en-Provence (2008, 55&prime; for Ina, Arte and France 2), De m\u00e9moire d\u2019orchestre with the Orchestre National de France (2004, 2 x 43&prime; for Arte), and Mozart, Ligeti et Le Banquet (2001, 52&prime; for Mezzo).<\/p>\n<p style=\"text-align: justify;\">His documentary work has given him the opportunity to work with the Italian conductor and harpsichordist Rinaldo Alessandrini, on Vivaldi\u2019s Glorias (2010, 43&prime; for Arte), Rinaldo Alessandrini enregistre les Concertos Brandebourgeois (2005, 43&prime; for Na\u00efve, Mezzo and Classica) and, just recently, Les Quatre Saisons d\u2019Antoine (2012, 35\u2018, France 3) co-directed with Gordon B\u00e9ziat. In collaboration with Marc Minkowski, he directed Les musiciens du Louvre &#8211; Paroles d&rsquo;orchestre (2003, 52&prime; for France 2), Marc Minkowski r\u00e9p\u00e8te La Belle H\u00e9l\u00e8ne (2000, 26&prime; for Mezzo), Pour Sainte-C\u00e9cile (2009, 88&prime; for Arte), Berlioz \u00e0 Versailles (2011, 90\u2019, for Arte) and the opera-documentary Pell\u00e9as et M\u00e9lisande, le chant des aveugles, directed by Olivier Py, released in cinemas in March 2009. During the 2007 edition of the Verbier Festival, Philippe B\u00e9ziat directed the live streaming of 11 concerts over the Internet. In addition, he did the filming for La pietra del paragone, by Gioacchino Rossini, directed by G.B.Corsetti and Pierrick Sorin (the DVD of which won the Diapason d\u2019Or), Richard Wagner\u2019s Der Ring des Nibelungen, and Claude Debussy\u2019s Pell\u00e9as et M\u00e9lisande, both in productions by Robert Wilson, Tourbillons by Georges Aperghis and Olivier Cadiot, Ta Bouche by Maurice Yvain, and Jacques Offenbach\u2019s Docteur Ox by the company Les Brigands, Les Contes d\u2019Hoffmann directed by Olivier Py and recently Caligula by Nicolas Le Riche and Guillaume Gallienne as well as Ring Saga, a version of Richard Wagner\u2019s The Ring of the Niebelung directed by Antoine Gindt.<\/p>\n<p style=\"text-align: justify;\">Philippe B\u00e9ziat has also directed several fictional short films. His film Noces, recounting the relationship between Ramuz and Stravinsky around the creation of the eponymous work, was released in February 2012. October of the same year sees the release of Traviata et nous, an opera-documentary on the work done by director Jean-Fran\u00e7ois Sivadier within the framework of the 2011 Aix-en-Provence Festival, with Natalie Dessay, and Louis Langr\u00e9e conducting the London Symphony Orchestra, broadcasted notably at New York Film Festival 2012.<\/p>\n<p style=\"text-align: justify;\">Recently, he shot <em>Giordano Bruno<\/em>, Francesco Filidei\u2019s opera staged by Antoine Gindt (2016), <em>Monteverdi, aux sources de l\u2019op\u00e9ra<\/em>, broadcasted on Arte in June 2017, and <em>Pr\u00e9vert, paroles inattendues, <\/em>broadcasted on France 2 in October 2017.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6020\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2018\/06\/Beziat.jpg\" alt=\"\" width=\"567\" height=\"756\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2018\/06\/Beziat.jpg 567w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2018\/06\/Beziat-225x300.jpg 225w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/p>\n<hr \/>\n<p><strong>\u00a0Cet artiste a particip\u00e9 au 19PaulFort \u00e0 :<\/strong><\/p>\n<p><a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2018\/06\/05\/rencontre-200-motels-de-frank-zappa-presentation-du-projet-de13-juin-2018\/\">&gt; La soir\u00e9e de m\u00e9c\u00e9nat (Concert) pour <em>200 Motels,<\/em> de Franck Zappa, le 13 juin 2018<\/a><\/p>\n<p>Une projection des op\u00e9ras \u00ab\u00a0Aliados\u00a0\u00bb et \u00ab\u00a0Giordano Bruno\u00a0\u00bb, les 6 et 7 d\u00e9cembre 2016<br \/>\n<a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/11\/27\/audiovisuel-operas-filmes-aliados-et-giordano-bruno-6-et-7-decembre-2016\/\">&gt; Lien vers l&rsquo;\u00e9v\u00e9nement<\/a><strong><br \/>\n<\/strong><\/p>\n<p>Un concert, \u00ab\u00a0La nuit hallucin\u00e9e\u00a0\u00bb, op\u00e9ra radiophonique, en mars 2013.<br \/>\n<a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/06\/01\/concert-tm-aliados-allies-un-opera-du-temps-reel-28-et-29-mars-2013\/\">&gt; Lien vers l&rsquo;\u00e9v\u00e9nement<\/a><\/p>\n<p>Un concert &#8211; T&amp;M Aliados (Alli\u00e9s) \u00ab\u00a0Un op\u00e9ra du temps r\u00e9el\u00a0\u00bb les 28 et 29 mars 2013.<br \/>\n<a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/06\/01\/concert-la-nuit-hallucinee-opera-radiophonique-de-sebastian-rivas-mars-2013\/\">&gt; Lien vers l&rsquo;\u00e9v\u00e9nement<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Philippe B\u00e9ziat R\u00e9alisateur (&gt; English below) Philippe B\u00e9ziat a r\u00e9alis\u00e9 de nombreux films documentaires tels que Passions d\u2019op\u00e9ra \u2013 60 ans d\u2019art lyrique \u00e0 Aix-en-Provence (2008) ou De m\u00e9moire d\u2019orchestre avec l\u2019Orchestre National de France (2004). Il a collabor\u00e9 avec le chef et claveciniste italien Rinaldo Alessandrini pour, entre autres, les Gloria de Vivaldi (2010)&hellip;<a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2016\/11\/23\/beziat-philippe\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">B\u00c9ZIAT Philippe \u2022<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,32,20,19],"tags":[],"class_list":["post-4180","post","type-post","status-publish","format-standard","hentry","category-artistes-invites","category-audiovisuel","category-par-nom","category-par-pratique-artistique"],"_links":{"self":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/4180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/comments?post=4180"}],"version-history":[{"count":13,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/4180\/revisions"}],"predecessor-version":[{"id":6026,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/4180\/revisions\/6026"}],"wp:attachment":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/media?parent=4180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/categories?post=4180"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/tags?post=4180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}