{"id":7871,"date":"2019-09-07T18:26:27","date_gmt":"2019-09-07T17:26:27","guid":{"rendered":"http:\/\/www.19paulfort.com\/galerie\/?p=7871"},"modified":"2025-03-01T17:28:35","modified_gmt":"2025-03-01T16:28:35","slug":"exposition-en-quete-de-linsaisissable-25-septembre-20-octobre-2019","status":"publish","type":"post","link":"http:\/\/www.19paulfort.com\/galerie\/index.php\/2019\/09\/07\/exposition-en-quete-de-linsaisissable-25-septembre-20-octobre-2019\/","title":{"rendered":"09 &#8211; 25 septembre  \/ 20 octobre &#8211; Exposition &#8211; \u00ab\u00a0En qu\u00eate de l&rsquo;insaisissable\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Prochaine exposition : <\/strong><\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #a1192d;\">\u00ab\u00a0En qu\u00eate de l&rsquo;insaisissable\u00a0\u00bb<\/span><br \/>\ndu mercredi 25 septembre<br \/>\nau dimanche 20 octobre 2019<br \/>\ntous les jours de 16h \u00e0 21h<\/h1>\n<p style=\"text-align: justify;\">Cette exposition pr\u00e9sente trois artistes de renomm\u00e9e internationale. <a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2019\/07\/18\/giroud-nicole\/\">Nicole Giroud<\/a>, qui d\u00e9fie la pesanteur, l&rsquo;\u00e9quilibre&#8230; \u00ab Ses \u0153uvres explorent la tension entre la vie, la mortalit\u00e9 et la fragilit\u00e9 de l&rsquo;existence. \u00bb. <a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2019\/09\/07\/chevallier-florence\/\">Florence Chevallier<\/a>, l&rsquo;\u0153il tactile de la photographie, qui saisit l&rsquo;insaisissable du corps, et Julien Carretero, \u00ab un design \u00e0 mains nues, sensuel et auto produit inscrit dans la ligne sinueuse des pi\u00e8ces uniques \/ industrielles d\u2019un Gaetano Pesce, qui rappelle l\u2019impossibilit\u00e9 du designer \u00e0 rester une pure t\u00eate pensante mais bien, aussi et surtout, un artisan au c\u0153ur du process de fabrication. \u00bb<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7826\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/07\/Giroud.jpg\" alt=\"\" width=\"1240\" height=\"1753\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/07\/Giroud.jpg 1240w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/07\/Giroud-212x300.jpg 212w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/07\/Giroud-768x1086.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/07\/Giroud-724x1024.jpg 724w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/07\/Giroud-750x1060.jpg 750w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7840\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/08\/invitChevallier.jpg\" alt=\"\" width=\"1240\" height=\"1753\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/08\/invitChevallier.jpg 1240w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/08\/invitChevallier-212x300.jpg 212w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/08\/invitChevallier-768x1086.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/08\/invitChevallier-724x1024.jpg 724w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/08\/invitChevallier-750x1060.jpg 750w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7879\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/09\/Carretero.jpg\" alt=\"\" width=\"1240\" height=\"1753\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/09\/Carretero.jpg 1240w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/09\/Carretero-212x300.jpg 212w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/09\/Carretero-768x1086.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/09\/Carretero-724x1024.jpg 724w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/09\/Carretero-750x1060.jpg 750w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><\/p>\n<div id='gallery-1' class='gallery galleryid-7871 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/img_4757\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/IMG_4757-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/img_4772\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/IMG_4772-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/img_4773\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/IMG_4773-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/IMG_4773-150x150.jpg 150w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/IMG_4773-768x775.jpg 768w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/IMG_4773-1015x1024.jpg 1015w, http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/IMG_4773-750x756.jpg 750w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08857\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08857-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08843\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08843-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08870\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08870-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08894\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08894-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08933\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08933-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08930\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08930-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08929\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08929-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08921\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08921-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.19paulfort.com\/galerie\/dsc08928\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"http:\/\/www.19paulfort.com\/galerie\/wp-content\/uploads\/2019\/10\/DSC08928-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Prochaine exposition : \u00ab\u00a0En qu\u00eate de l&rsquo;insaisissable\u00a0\u00bb du mercredi 25 septembre au dimanche 20 octobre 2019 tous les jours de 16h \u00e0 21h Cette exposition pr\u00e9sente trois artistes de renomm\u00e9e internationale. Nicole Giroud, qui d\u00e9fie la pesanteur, l&rsquo;\u00e9quilibre&#8230; \u00ab Ses \u0153uvres explorent la tension entre la vie, la mortalit\u00e9 et la fragilit\u00e9 de l&rsquo;existence. \u00bb.&hellip;<a href=\"http:\/\/www.19paulfort.com\/galerie\/index.php\/2019\/09\/07\/exposition-en-quete-de-linsaisissable-25-septembre-20-octobre-2019\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">09 &#8211; 25 septembre  \/ 20 octobre &#8211; Exposition &#8211; \u00ab\u00a0En qu\u00eate de l&rsquo;insaisissable\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,7,16],"tags":[],"class_list":["post-7871","post","type-post","status-publish","format-standard","hentry","category-evenements-2019","category-evenements-passes","category-expositions"],"_links":{"self":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/7871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/comments?post=7871"}],"version-history":[{"count":4,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/7871\/revisions"}],"predecessor-version":[{"id":12920,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/posts\/7871\/revisions\/12920"}],"wp:attachment":[{"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/media?parent=7871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/categories?post=7871"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.19paulfort.com\/galerie\/index.php\/wp-json\/wp\/v2\/tags?post=7871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}